{"id":44,"count":3,"description":"","link":"https:\/\/www2.energia.coop\/colombia\/categoria\/blog\/","name":"Blog","slug":"blog","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blog - Energia Cooperativa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www2.energia.coop\/colombia\/categoria\/blog\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blog - Energia Cooperativa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www2.energia.coop\/colombia\/categoria\/blog\/\" \/>\n<meta property=\"og:site_name\" content=\"Energia Cooperativa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www2.energia.coop\\\/colombia\\\/categoria\\\/blog\\\/\",\"url\":\"https:\\\/\\\/www2.energia.coop\\\/colombia\\\/categoria\\\/blog\\\/\",\"name\":\"Blog - Energia Cooperativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www2.energia.coop\\\/colombia\\\/#website\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www2.energia.coop\\\/colombia\\\/#website\",\"url\":\"https:\\\/\\\/www2.energia.coop\\\/colombia\\\/\",\"name\":\"Energia Cooperativa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www2.energia.coop\\\/colombia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blog - Energia Cooperativa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www2.energia.coop\/colombia\/categoria\/blog\/","og_locale":"pt_BR","og_type":"article","og_title":"Blog - Energia Cooperativa","og_url":"https:\/\/www2.energia.coop\/colombia\/categoria\/blog\/","og_site_name":"Energia Cooperativa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www2.energia.coop\/colombia\/categoria\/blog\/","url":"https:\/\/www2.energia.coop\/colombia\/categoria\/blog\/","name":"Blog - Energia Cooperativa","isPartOf":{"@id":"https:\/\/www2.energia.coop\/colombia\/#website"},"inLanguage":"pt-BR"},{"@type":"WebSite","@id":"https:\/\/www2.energia.coop\/colombia\/#website","url":"https:\/\/www2.energia.coop\/colombia\/","name":"Energia Cooperativa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www2.energia.coop\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www2.energia.coop\/colombia\/wp-json\/wp\/v2\/categories\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.energia.coop\/colombia\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www2.energia.coop\/colombia\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www2.energia.coop\/colombia\/wp-json\/wp\/v2\/posts?categories=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}